{"id":18,"date":"2023-09-19T15:56:55","date_gmt":"2023-09-19T18:56:55","guid":{"rendered":"https:\/\/assai.com.br\/adegaassai\/destilados-para-voce\/?page_id=18"},"modified":"2026-04-30T10:56:33","modified_gmt":"2026-04-30T13:56:33","slug":"home","status":"publish","type":"page","link":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/","title":{"rendered":"Home"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"front-page.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-18","page","type-page","status-publish","hentry"],"acf":{"photo_gallery":{"banners_desktop":[[{"id":1082,"title":"BANNER BALLLA","caption":"","full_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA.jpg","thumbnail_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-150x150.jpg","large_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1024x219.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-300x64.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-768x164.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1536x328.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA.jpg 1920w","medium_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-300x64.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1024x219.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-768x164.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1536x328.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA.jpg 1920w","media_details":{"width":1920,"height":410,"sizes":{"medium":{"file":"BANNER-BALLLA-300x64.jpg","width":300,"height":64,"mime-type":"image\/jpeg","filesize":6519,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-300x64.jpg"},"large":{"file":"BANNER-BALLLA-1024x219.jpg","width":1024,"height":219,"mime-type":"image\/jpeg","filesize":41091,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1024x219.jpg"},"thumbnail":{"file":"BANNER-BALLLA-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6586,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-150x150.jpg"},"medium_large":{"file":"BANNER-BALLLA-768x164.jpg","width":768,"height":164,"mime-type":"image\/jpeg","filesize":26988,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-768x164.jpg"},"1536x1536":{"file":"BANNER-BALLLA-1536x328.jpg","width":1536,"height":328,"mime-type":"image\/jpeg","filesize":73166,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1536x328.jpg"},"destaque-noticia":{"file":"BANNER-BALLLA-540x345.jpg","width":540,"height":345,"mime-type":"image\/jpeg","filesize":33388,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-540x345.jpg"},"thumb-noticia":{"file":"BANNER-BALLLA-485x329.jpg","width":485,"height":329,"mime-type":"image\/jpeg","filesize":30008,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-485x329.jpg"},"carrossel":{"file":"BANNER-BALLLA-670x410.jpg","width":670,"height":410,"mime-type":"image\/jpeg","filesize":48644,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-670x410.jpg"},"quadrado":{"file":"BANNER-BALLLA-700x410.jpg","width":700,"height":410,"mime-type":"image\/jpeg","filesize":49980,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-700x410.jpg"},"garrafa":{"file":"BANNER-BALLLA-76x300.jpg","width":76,"height":300,"mime-type":"image\/jpeg","filesize":3774,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-76x300.jpg"},"logo-fornecedores":{"file":"BANNER-BALLLA-250x250.jpg","width":250,"height":250,"mime-type":"image\/jpeg","filesize":14046,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-250x250.jpg"}}},"alt_text":"","url":"","target":""},{"id":953,"title":"bannercocaaa","caption":"","full_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa.jpg","thumbnail_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-150x150.jpg","large_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1024x219.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-300x64.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-768x164.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1536x328.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa.jpg 1920w","medium_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-300x64.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1024x219.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-768x164.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1536x328.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa.jpg 1920w","media_details":{"width":1920,"height":410,"sizes":{"medium":{"file":"bannercocaaa-300x64.jpg","width":300,"height":64,"mime-type":"image\/jpeg","filesize":4713,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-300x64.jpg"},"large":{"file":"bannercocaaa-1024x219.jpg","width":1024,"height":219,"mime-type":"image\/jpeg","filesize":25574,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1024x219.jpg"},"thumbnail":{"file":"bannercocaaa-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5677,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-150x150.jpg"},"medium_large":{"file":"bannercocaaa-768x164.jpg","width":768,"height":164,"mime-type":"image\/jpeg","filesize":17590,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-768x164.jpg"},"1536x1536":{"file":"bannercocaaa-1536x328.jpg","width":1536,"height":328,"mime-type":"image\/jpeg","filesize":44122,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1536x328.jpg"},"destaque-noticia":{"file":"bannercocaaa-540x345.jpg","width":540,"height":345,"mime-type":"image\/jpeg","filesize":22332,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-540x345.jpg"},"thumb-noticia":{"file":"bannercocaaa-485x329.jpg","width":485,"height":329,"mime-type":"image\/jpeg","filesize":20560,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-485x329.jpg"},"carrossel":{"file":"bannercocaaa-670x410.jpg","width":670,"height":410,"mime-type":"image\/jpeg","filesize":29271,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-670x410.jpg"},"quadrado":{"file":"bannercocaaa-700x410.jpg","width":700,"height":410,"mime-type":"image\/jpeg","filesize":30038,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-700x410.jpg"},"garrafa":{"file":"bannercocaaa-76x300.jpg","width":76,"height":300,"mime-type":"image\/jpeg","filesize":4043,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-76x300.jpg"},"logo-fornecedores":{"file":"bannercocaaa-250x250.jpg","width":250,"height":250,"mime-type":"image\/jpeg","filesize":10051,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-250x250.jpg"}}},"alt_text":"","url":"","target":""},{"id":291,"title":"destilados 2","caption":"","full_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2.jpg","thumbnail_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-150x150.jpg","large_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1024x213.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-300x63.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-768x160.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1536x320.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2.jpg 1920w","medium_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-300x63.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1024x213.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-768x160.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1536x320.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2.jpg 1920w","media_details":{"width":1920,"height":400,"sizes":{"medium":{"file":"destilados-2-300x63.jpg","width":300,"height":63,"mime-type":"image\/jpeg","filesize":9278,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-300x63.jpg"},"large":{"file":"destilados-2-1024x213.jpg","width":1024,"height":213,"mime-type":"image\/jpeg","filesize":43266,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1024x213.jpg"},"thumbnail":{"file":"destilados-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":10738,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-150x150.jpg"},"medium_large":{"file":"destilados-2-768x160.jpg","width":768,"height":160,"mime-type":"image\/jpeg","filesize":28246,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-768x160.jpg"},"1536x1536":{"file":"destilados-2-1536x320.jpg","width":1536,"height":320,"mime-type":"image\/jpeg","filesize":75318,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1536x320.jpg"},"destaque-noticia":{"file":"destilados-2-540x345.jpg","width":540,"height":345,"mime-type":"image\/jpeg","filesize":41347,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-540x345.jpg"},"thumb-noticia":{"file":"destilados-2-485x329.jpg","width":485,"height":329,"mime-type":"image\/jpeg","filesize":37674,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-485x329.jpg"},"carrossel":{"file":"destilados-2-670x400.jpg","width":670,"height":400,"mime-type":"image\/jpeg","filesize":57219,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-670x400.jpg"},"quadrado":{"file":"destilados-2-700x400.jpg","width":700,"height":400,"mime-type":"image\/jpeg","filesize":58901,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-700x400.jpg"},"garrafa":{"file":"destilados-2-76x300.jpg","width":76,"height":300,"mime-type":"image\/jpeg","filesize":7992,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-76x300.jpg"}}},"alt_text":"","url":"https:\/\/assai.com.br\/adegaassai\/destilados-para-voce\/tipos-de-destilados\/","target":""},{"id":293,"title":"banner drinks","caption":"","full_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks.jpg","thumbnail_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-150x150.jpg","large_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1024x213.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-300x63.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-768x160.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1536x320.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks.jpg 1920w","medium_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-300x63.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1024x213.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-768x160.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1536x320.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks.jpg 1920w","media_details":{"width":1920,"height":400,"sizes":{"medium":{"file":"banner-drinks-300x63.jpg","width":300,"height":63,"mime-type":"image\/jpeg","filesize":6386,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-300x63.jpg"},"large":{"file":"banner-drinks-1024x213.jpg","width":1024,"height":213,"mime-type":"image\/jpeg","filesize":41592,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1024x213.jpg"},"thumbnail":{"file":"banner-drinks-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6708,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-150x150.jpg"},"medium_large":{"file":"banner-drinks-768x160.jpg","width":768,"height":160,"mime-type":"image\/jpeg","filesize":25923,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-768x160.jpg"},"1536x1536":{"file":"banner-drinks-1536x320.jpg","width":1536,"height":320,"mime-type":"image\/jpeg","filesize":76091,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1536x320.jpg"},"destaque-noticia":{"file":"banner-drinks-540x345.jpg","width":540,"height":345,"mime-type":"image\/jpeg","filesize":34936,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-540x345.jpg"},"thumb-noticia":{"file":"banner-drinks-485x329.jpg","width":485,"height":329,"mime-type":"image\/jpeg","filesize":30700,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-485x329.jpg"},"carrossel":{"file":"banner-drinks-670x400.jpg","width":670,"height":400,"mime-type":"image\/jpeg","filesize":49475,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-670x400.jpg"},"quadrado":{"file":"banner-drinks-700x400.jpg","width":700,"height":400,"mime-type":"image\/jpeg","filesize":52419,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-700x400.jpg"},"garrafa":{"file":"banner-drinks-76x300.jpg","width":76,"height":300,"mime-type":"image\/jpeg","filesize":4556,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-76x300.jpg"}}},"alt_text":"","url":"https:\/\/assai.com.br\/adegaassai\/destilados-para-voce\/drinks\/","target":""}]],"banners_mobile":[[{"id":1082,"title":"BANNER BALLLA","caption":"","full_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA.jpg","thumbnail_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-150x150.jpg","large_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1024x219.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-300x64.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-768x164.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1536x328.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA.jpg 1920w","medium_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-300x64.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1024x219.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-768x164.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1536x328.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA.jpg 1920w","media_details":{"width":1920,"height":410,"sizes":{"medium":{"file":"BANNER-BALLLA-300x64.jpg","width":300,"height":64,"mime-type":"image\/jpeg","filesize":6519,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-300x64.jpg"},"large":{"file":"BANNER-BALLLA-1024x219.jpg","width":1024,"height":219,"mime-type":"image\/jpeg","filesize":41091,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1024x219.jpg"},"thumbnail":{"file":"BANNER-BALLLA-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6586,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-150x150.jpg"},"medium_large":{"file":"BANNER-BALLLA-768x164.jpg","width":768,"height":164,"mime-type":"image\/jpeg","filesize":26988,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-768x164.jpg"},"1536x1536":{"file":"BANNER-BALLLA-1536x328.jpg","width":1536,"height":328,"mime-type":"image\/jpeg","filesize":73166,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-1536x328.jpg"},"destaque-noticia":{"file":"BANNER-BALLLA-540x345.jpg","width":540,"height":345,"mime-type":"image\/jpeg","filesize":33388,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-540x345.jpg"},"thumb-noticia":{"file":"BANNER-BALLLA-485x329.jpg","width":485,"height":329,"mime-type":"image\/jpeg","filesize":30008,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-485x329.jpg"},"carrossel":{"file":"BANNER-BALLLA-670x410.jpg","width":670,"height":410,"mime-type":"image\/jpeg","filesize":48644,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-670x410.jpg"},"quadrado":{"file":"BANNER-BALLLA-700x410.jpg","width":700,"height":410,"mime-type":"image\/jpeg","filesize":49980,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-700x410.jpg"},"garrafa":{"file":"BANNER-BALLLA-76x300.jpg","width":76,"height":300,"mime-type":"image\/jpeg","filesize":3774,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-76x300.jpg"},"logo-fornecedores":{"file":"BANNER-BALLLA-250x250.jpg","width":250,"height":250,"mime-type":"image\/jpeg","filesize":14046,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2026\/04\/BANNER-BALLLA-250x250.jpg"}}},"alt_text":"","url":"","target":""},{"id":953,"title":"bannercocaaa","caption":"","full_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa.jpg","thumbnail_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-150x150.jpg","large_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1024x219.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-300x64.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-768x164.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1536x328.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa.jpg 1920w","medium_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-300x64.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1024x219.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-768x164.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1536x328.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa.jpg 1920w","media_details":{"width":1920,"height":410,"sizes":{"medium":{"file":"bannercocaaa-300x64.jpg","width":300,"height":64,"mime-type":"image\/jpeg","filesize":4713,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-300x64.jpg"},"large":{"file":"bannercocaaa-1024x219.jpg","width":1024,"height":219,"mime-type":"image\/jpeg","filesize":25574,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1024x219.jpg"},"thumbnail":{"file":"bannercocaaa-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":5677,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-150x150.jpg"},"medium_large":{"file":"bannercocaaa-768x164.jpg","width":768,"height":164,"mime-type":"image\/jpeg","filesize":17590,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-768x164.jpg"},"1536x1536":{"file":"bannercocaaa-1536x328.jpg","width":1536,"height":328,"mime-type":"image\/jpeg","filesize":44122,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-1536x328.jpg"},"destaque-noticia":{"file":"bannercocaaa-540x345.jpg","width":540,"height":345,"mime-type":"image\/jpeg","filesize":22332,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-540x345.jpg"},"thumb-noticia":{"file":"bannercocaaa-485x329.jpg","width":485,"height":329,"mime-type":"image\/jpeg","filesize":20560,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-485x329.jpg"},"carrossel":{"file":"bannercocaaa-670x410.jpg","width":670,"height":410,"mime-type":"image\/jpeg","filesize":29271,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-670x410.jpg"},"quadrado":{"file":"bannercocaaa-700x410.jpg","width":700,"height":410,"mime-type":"image\/jpeg","filesize":30038,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-700x410.jpg"},"garrafa":{"file":"bannercocaaa-76x300.jpg","width":76,"height":300,"mime-type":"image\/jpeg","filesize":4043,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-76x300.jpg"},"logo-fornecedores":{"file":"bannercocaaa-250x250.jpg","width":250,"height":250,"mime-type":"image\/jpeg","filesize":10051,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2025\/09\/bannercocaaa-250x250.jpg"}}},"alt_text":"","url":"","target":""},{"id":291,"title":"destilados 2","caption":"","full_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2.jpg","thumbnail_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-150x150.jpg","large_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1024x213.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-300x63.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-768x160.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1536x320.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2.jpg 1920w","medium_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-300x63.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1024x213.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-768x160.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1536x320.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2.jpg 1920w","media_details":{"width":1920,"height":400,"sizes":{"medium":{"file":"destilados-2-300x63.jpg","width":300,"height":63,"mime-type":"image\/jpeg","filesize":9278,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-300x63.jpg"},"large":{"file":"destilados-2-1024x213.jpg","width":1024,"height":213,"mime-type":"image\/jpeg","filesize":43266,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1024x213.jpg"},"thumbnail":{"file":"destilados-2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":10738,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-150x150.jpg"},"medium_large":{"file":"destilados-2-768x160.jpg","width":768,"height":160,"mime-type":"image\/jpeg","filesize":28246,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-768x160.jpg"},"1536x1536":{"file":"destilados-2-1536x320.jpg","width":1536,"height":320,"mime-type":"image\/jpeg","filesize":75318,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-1536x320.jpg"},"destaque-noticia":{"file":"destilados-2-540x345.jpg","width":540,"height":345,"mime-type":"image\/jpeg","filesize":41347,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-540x345.jpg"},"thumb-noticia":{"file":"destilados-2-485x329.jpg","width":485,"height":329,"mime-type":"image\/jpeg","filesize":37674,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-485x329.jpg"},"carrossel":{"file":"destilados-2-670x400.jpg","width":670,"height":400,"mime-type":"image\/jpeg","filesize":57219,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-670x400.jpg"},"quadrado":{"file":"destilados-2-700x400.jpg","width":700,"height":400,"mime-type":"image\/jpeg","filesize":58901,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-700x400.jpg"},"garrafa":{"file":"destilados-2-76x300.jpg","width":76,"height":300,"mime-type":"image\/jpeg","filesize":7992,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/03\/destilados-2-76x300.jpg"}}},"alt_text":"","url":"https:\/\/assai.com.br\/adegaassai\/destilados-para-voce\/tipos-de-destilados\/","target":""},{"id":293,"title":"banner drinks","caption":"","full_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks.jpg","thumbnail_image_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-150x150.jpg","large_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1024x213.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-300x63.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-768x160.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1536x320.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks.jpg 1920w","medium_srcset":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-300x63.jpg 300w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1024x213.jpg 1024w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-768x160.jpg 768w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1536x320.jpg 1536w, https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks.jpg 1920w","media_details":{"width":1920,"height":400,"sizes":{"medium":{"file":"banner-drinks-300x63.jpg","width":300,"height":63,"mime-type":"image\/jpeg","filesize":6386,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-300x63.jpg"},"large":{"file":"banner-drinks-1024x213.jpg","width":1024,"height":213,"mime-type":"image\/jpeg","filesize":41592,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1024x213.jpg"},"thumbnail":{"file":"banner-drinks-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":6708,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-150x150.jpg"},"medium_large":{"file":"banner-drinks-768x160.jpg","width":768,"height":160,"mime-type":"image\/jpeg","filesize":25923,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-768x160.jpg"},"1536x1536":{"file":"banner-drinks-1536x320.jpg","width":1536,"height":320,"mime-type":"image\/jpeg","filesize":76091,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-1536x320.jpg"},"destaque-noticia":{"file":"banner-drinks-540x345.jpg","width":540,"height":345,"mime-type":"image\/jpeg","filesize":34936,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-540x345.jpg"},"thumb-noticia":{"file":"banner-drinks-485x329.jpg","width":485,"height":329,"mime-type":"image\/jpeg","filesize":30700,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-485x329.jpg"},"carrossel":{"file":"banner-drinks-670x400.jpg","width":670,"height":400,"mime-type":"image\/jpeg","filesize":49475,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-670x400.jpg"},"quadrado":{"file":"banner-drinks-700x400.jpg","width":700,"height":400,"mime-type":"image\/jpeg","filesize":52419,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-700x400.jpg"},"garrafa":{"file":"banner-drinks-76x300.jpg","width":76,"height":300,"mime-type":"image\/jpeg","filesize":4556,"source_url":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-content\/uploads\/2024\/04\/banner-drinks-76x300.jpg"}}},"alt_text":"","url":"https:\/\/assai.com.br\/adegaassai\/destilados-para-voce\/drinks\/","target":""}],[]]}},"_links":{"self":[{"href":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-json\/wp\/v2\/pages\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-json\/wp\/v2\/comments?post=18"}],"version-history":[{"count":5,"href":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-json\/wp\/v2\/pages\/18\/revisions"}],"predecessor-version":[{"id":417,"href":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-json\/wp\/v2\/pages\/18\/revisions\/417"}],"wp:attachment":[{"href":"https:\/\/www.assai.com.br\/adegaassai\/destilados-para-voce\/wp-json\/wp\/v2\/media?parent=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}